{"id":226065,"date":"2024-04-22T15:18:38","date_gmt":"2024-04-22T15:18:38","guid":{"rendered":"https:\/\/arc.coop\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/"},"modified":"2024-04-22T16:05:55","modified_gmt":"2024-04-22T16:05:55","slug":"comunidades-energeticas-mucho-mas-que-placas-solares-colectivas","status":"publish","type":"post","link":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/","title":{"rendered":"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas"},"content":{"rendered":"<h5 style=\"text-align: center;\"><strong>Nuestra apuesta por acompa\u00f1ar los proyectos alineados con una transici\u00f3n ecol\u00f3gica justa y democr\u00e1tica, estamos ofreciendo seguros espec\u00edficos para cubrir las necesidades aseguradoras de las comunidades energ\u00e9ticas. Estos colectivos, nacidos de la voluntad y la determinaci\u00f3n de grupos de personas para organizarse horizontalmente y de manera autogestionada, trabajan para un sistema energ\u00e9tico sostenible al servicio del bien com\u00fan, con un acceso justo a la energ\u00eda de fuente renovable.\u00a0<\/strong><\/h5>\n<h5 style=\"text-align: center;\"><strong>Hemos querido charlar con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para poner nuestro granito de arena y convertirnos, una vez m\u00e1s, en altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.<\/strong><\/h5>\n<h5 style=\"text-align: center;\"><strong>Para redactar este reportaje hemos contado con las aportaciones de Francesc Casadell\u00e0, miembro del equipo t\u00e9cnico de Som Energia y miembro del equipo impulsor de Som Comunitats; Gaia D&#8217;Elia, coordinadora de BATEC; Alfonso Garc\u00eda M\u00e1rquez, presidente de la Uni\u00f3n Renovables; y Mois\u00e9s Mart\u00ednez, responsable del sello CEL Coop de la Federaci\u00f3 de Cooperatives de Treball de Catalunya (FCTC).<\/strong><\/h5>\n<div id=\"attachment_226058\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-226058\" class=\"size-full wp-image-226058\" src=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia.jpg\" alt=\"\" width=\"1024\" height=\"300\" srcset=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia-200x59.jpg 200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia-300x88.jpg 300w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia-400x117.jpg 400w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia-600x176.jpg 600w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia-768x225.jpg 768w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia-800x234.jpg 800w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/entrevistes-comunitats-energetiques-copia.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-226058\" class=\"wp-caption-text\">Francesc Casadell\u00e0 (Som Comunitats), Gaia D&#8217;Elia (BATEC), Alfonso Garc\u00eda M\u00e1rquez (Uni\u00f3n Renovables) y Mois\u00e9s<\/p><\/div>\n<h4><strong>Una primera aproximaci\u00f3n a las comunidades energ\u00e9ticas<\/strong><\/h4>\n<p>Una de las primeras dudas que pueden surgir al hablar de comunidades energ\u00e9ticas es entender exactamente qu\u00e9 son. Una primera aproximaci\u00f3n ser\u00eda la de<strong> agrupaciones de diferentes agentes con el objetivo de obtener un modelo energ\u00e9tico 100% renovable y sostenible desde la transformaci\u00f3n social democr\u00e1tica. <\/strong>[1] Esto se materializa, en muchas ocasiones, en grupos de personas y entidades que se organizan para producir y distribuir energ\u00eda de fuente renovable.<\/p>\n<p>Pero m\u00e1s all\u00e1 del acceso justo, proporcionado y asequible a los recursos energ\u00e9ticos, \u00bfqu\u00e9 m\u00e1s proponen las comunidades energ\u00e9ticas? Gaia D&#8217;Elia, coordinadora de <a href=\"https:\/\/batec.coop\/\">BATEC<\/a>, nos cuenta c\u00f3mo estas agrupaciones \u00abllevan a cabo una tarea monumental para la alfabetizaci\u00f3n energ\u00e9tica, la formaci\u00f3n y el acceso a la informaci\u00f3n que conlleva un <strong>proceso de empoderamiento.<\/strong>\u00bb Para BATEC &#8211; proyecto de intercooperaci\u00f3n socioecon\u00f3mica de entidades cooperativas y asociativas que trabaja para ser un referente en la transici\u00f3n energ\u00e9tica hacia un modelo sostenible, justo y democr\u00e1tico &#8211; una comunidad energ\u00e9tica \u00abno solo hace referencia a la generaci\u00f3n y distribuci\u00f3n de kWh, sino tambi\u00e9n al <strong>conocimiento con actividades de divulgaci\u00f3n y fomento de la participaci\u00f3n.\u00bb<\/strong><\/p>\n<p>Gaia nos comenta como las comunidades energ\u00e9ticas tambi\u00e9n apuestan, por ejemplo, por la <strong>movilidad el\u00e9ctrica sostenible<\/strong> \u00abdesde el urbanismo, la promoci\u00f3n del transporte p\u00fablico (o p\u00fablico-comunitario) o el impulso de compras colectivas de bicicletas, la implementaci\u00f3n de cargadores y veh\u00edculos el\u00e9ctricos de uso compartido.\u00bb<\/p>\n<p>Francesc Casadell\u00e0, miembro del equipo impulsor de <a href=\"https:\/\/somcomunitats.coop\/\">Som Comunitats<\/a>, comparte que la cuesti\u00f3n de reflexionar sobre qu\u00e9 pueden aportar las comunidades energ\u00e9ticas fue una de las preguntas que quisieron responder en el <a href=\"https:\/\/blog.somenergia.coop\/som-energia\/comunidades-energeticas\/2023\/06\/1a-trobada-de-comunitats-energetiques-de-leconomia-social\/\" target=\"_blank\" rel=\"noopener\">1er encuentro de la red de Comunidades Energ\u00e9ticas de la econom\u00eda social de Catalu\u00f1a<\/a>: \u00abSurgieron un <strong>abanico de servicios<\/strong> que ya estaban llevando a cabo, desde compras colectivas de le\u00f1a y pellet, hasta servicios intangibles como asesoramientos energ\u00e9ticos o compartir espacios para huertos comunitarios.\u00bb<\/p>\n<div id=\"attachment_225856\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-225856\" class=\"wp-image-225856 size-large\" src=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-200x150.jpg 200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-300x225.jpg 300w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-400x300.jpg 400w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-600x450.jpg 600w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-768x576.jpg 768w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-800x600.jpg 800w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-1024x768.jpg 1024w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa-1200x900.jpg 1200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/CELB_Diversa.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-225856\" class=\"wp-caption-text\">Autor\u00eda: BATEC<\/p><\/div>\n<h4>La capacidad transformadora de las comunidades energ\u00e9ticas<\/h4>\n<p>Es habitual, cuando hablamos de comunidades energ\u00e9ticas, referirse a su <strong>potencial transformador<\/strong>. Mois\u00e9s Mart\u00edenz, portavoz del sello <a href=\"https:\/\/www.cooperativestreball.coop\/agrupem\/cel-cooperatives\" target=\"_blank\" rel=\"noopener\">CEL Coop<\/a> que ha promovido recientemente <a href=\"https:\/\/www.cooperativestreball.coop\/\" target=\"_blank\" rel=\"noopener\">Cooperatives de Treball<\/a>, destaca esta capacidad de las comunidades energ\u00e9ticas \u00abya que ayudan a luchar contra la pobreza energ\u00e9tica y promueven una <strong>soberan\u00eda energ\u00e9tica<\/strong> en el \u00e1mbito local, permiten aprovechamiento directo de los recursos propios y una mejora en la <strong>democratizaci\u00f3n de la gesti\u00f3n de la energ\u00eda<\/strong> entre sus participantes con un <strong>empoderamiento muy grande.<\/strong>\u00bb Desde CEL Coop opinan que \u00abla proliferaci\u00f3n de las comunidades energ\u00e9ticas nos permite dar un salto cualitativo en la capacitaci\u00f3n de la ciudadan\u00eda para decidir c\u00f3mo generar y gestionar los recursos de manera colectiva.\u00bb<\/p>\n<blockquote>\n<h4><strong>Gaia D&#8217;Elia: \u00abLas comunidades energ\u00e9ticas, como estructura de organizaci\u00f3n popular, son una herramienta con mucho potencial transformador\u00bb<\/strong><\/h4>\n<\/blockquote>\n<p>En esta misma l\u00ednea se muestra Alfonso Garc\u00eda M\u00e1rquez, presidente de <a href=\"https:\/\/www.unionrenovables.coop\/\" target=\"_blank\" rel=\"noopener\">Uni\u00f3n Renovables<\/a>, la uni\u00f3n de cooperativas de personas consumidoras y usuarias de energ\u00edas renovables vinculadas a <a href=\"https:\/\/reas.red\/\" target=\"_blank\" rel=\"noopener\">REAS Red de Redes<\/a>. Para Garc\u00eda M\u00e1rquez, cuando un proyecto realmente funciona como una comunidad energ\u00e9tica \u00abpermite la <strong>toma de conciencia de las personas y la socializaci\u00f3n\u00a0<\/strong>sobre el gran desaf\u00edo en el que nos encontramos de transici\u00f3n de los combustibles f\u00f3siles hacia las energ\u00edas renovables.\u00bb Alfonso a\u00f1ade que, adem\u00e1s del empoderamiento de la ciudadan\u00eda en materia energ\u00e9tica, las comunidades energ\u00e9ticas \u00abgeneran un reto en los territorios y sobre todo un <strong>h\u00e1bito colectivo y de socializaci\u00f3n de retos diarios.<\/strong>\u00bb<\/p>\n<p>Para la coordinadora de BATEC, \u00ablas comunidades energ\u00e9ticas, como <strong>estructura de organizaci\u00f3n popular<\/strong>, son una herramienta con un gran potencial transformador, ya que hablamos de satisfacer necesidades b\u00e1sicas.\u00bb Gaia D&#8217;Elia nos comenta que \u00abcubrir las necesidades b\u00e1sicas de manera comunitaria, democr\u00e1tica, participativa y sostenible es un reto, pero es definitivamente la mejor alternativa ante otros modelos que se encuentran en manos de oligopolios y que se enriquecen a costa de nuestras necesidades.\u00bb<\/p>\n<div id=\"attachment_225861\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-225861\" class=\"wp-image-225861 size-large\" src=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-200x113.jpg 200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-300x169.jpg 300w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-400x225.jpg 400w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-600x338.jpg 600w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-768x432.jpg 768w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-800x450.jpg 800w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-1024x576.jpg 1024w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-1200x675.jpg 1200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221807965_366782012b_k-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-225861\" class=\"wp-caption-text\">2o Encuentro Comunidades Energ\u00e9ticas de la Econom\u00eda Solidaria (Manresa, 2023). Autor\u00eda: Som Comunitats<\/p><\/div>\n<h4>Los v\u00ednculos de las comunidades energ\u00e9ticas con la econom\u00eda social y solidaria<\/h4>\n<p>Algunas organizaciones y empresas de la econom\u00eda social y solidaria (ESS) est\u00e1n participando de manera muy activa en la promoci\u00f3n de comunidades energ\u00e9ticas. BATEC, por ejemplo, es un <strong>proyecto de intercooperaci\u00f3n que nace de la ESS<\/strong> en Barcelona. Som Comunitats, por su lado, es un <strong>proyecto conjunto entre siete entidades de la ESS catalana.<\/strong> El caso de Uni\u00f3n Renovables tambi\u00e9n es representativo porque funciona como<strong> sectorial de las cooperativas de consumidores de energ\u00eda renovable de la red de redes de la econom\u00eda alternativa y solidaria<\/strong>, REAS Red de Redes.<\/p>\n<p>Seg\u00fan Alfonso Garc\u00eda M\u00e1rquez, de Uni\u00f3n Renovables, las comunidades energ\u00e9ticas tienen una serie de caracter\u00edsticas, como su objetivo, la propiedad compartida, la gobernanza y la toma de decisiones, que permiten que se \u00abpuedan establecer conexiones de forma muy natural con <strong>los principios y valores de la ESS<\/strong> como son la equidad, el trabajo digno, la sostenibilidad ecol\u00f3gica, la cooperaci\u00f3n, el reparto justo de la riqueza y el compromiso con el entorno.\u00bb<\/p>\n<blockquote>\n<h4>Mois\u00e8s Mart\u00ednez: \u00abLa proliferaci\u00f3n de las comunidades energ\u00e9ticas nos permite dar un salto cualitativo en la capacitaci\u00f3n de la ciudadan\u00eda para decidir como generar y gestionar los recursos de manera colectiva\u00bb<\/h4>\n<\/blockquote>\n<p>Por su lado, Francesc Casadell\u00e0 nos comparte como el salto de escala de las comunidades energ\u00e9ticas \u00abpuede tener un <strong>impacto muy grande en el impulso del mercado social y la ESS<\/strong>\u00ab, ya que son entidades jur\u00eddicas sin \u00e1nimo de lucro, enraizadas en el territorio, juntamente con el hecho que el sector energ\u00e9tico es un sector tractor de la econom\u00eda.<\/p>\n<div id=\"attachment_225870\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-225870\" class=\"size-large wp-image-225870\" src=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-200x113.jpg 200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-300x169.jpg 300w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-400x225.jpg 400w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-600x338.jpg 600w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-768x432.jpg 768w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-800x450.jpg 800w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-1024x576.jpg 1024w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-1200x675.jpg 1200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/53221689914_e996ac968a_k-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-225870\" class=\"wp-caption-text\">2o Encuentro Comunidades Energ\u00e9ticas de la Econom\u00eda Solidaria (Manresa, 2023). Autor\u00eda: Som Comunitats<\/p><\/div>\n<h4><strong>Las comunidades energ\u00e9ticas como palanca para la transformaci\u00f3n ecosocial<\/strong><\/h4>\n<p>Desde Ar\u00e7 Cooperativa, como parte del movimiento de la econom\u00eda solidaria, entendemos que las <strong>comunidades energ\u00e9ticas pueden ser punta de lanza de una necesaria <a href=\"https:\/\/arc.coop\/es\/2023\/05\/31\/arc-cooperativa-y-la-transicion-ecosocial-un-compromiso-de-presente-y-futuro\/\">transici\u00f3n ecosocial<\/a><\/strong>. Esta es una opini\u00f3n compartida por todas las voces que han participado en este reportaje. Desde el sello CEL Coop, Mois\u00e9s Mart\u00ednez opina \u00abque la gobernanza interna, la descentralizaci\u00f3n de la generaci\u00f3n, la gesti\u00f3n del consumo y actuar desde el mundo local son factores que potencian una <strong>transici\u00f3n energ\u00e9tica m\u00e1s coherente.<\/strong>\u00bb<\/p>\n<blockquote>\n<h4>Alfonso Garc\u00eda M\u00e1rquez: \u00abLas comunidades energ\u00e9ticas posibilitan el empoderamiento ciudadano y sit\u00faan el escenario fuera del &#8216;Matrix&#8217; en el que vivimos\u00bb<\/h4>\n<\/blockquote>\n<p>En esta misma l\u00ednea, desde Som Comuntiats creen que \u00abla soluci\u00f3n tendr\u00eda que pasar por las comunidades energ\u00e9ticas de la econom\u00eda social\u00bb. Francesc Casadell\u00e0 insiste que \u00abpara que esta <strong>transici\u00f3n ecol\u00f3gica sea justa y democr\u00e1tica<\/strong>, debemos descentralizar tambi\u00e9n el sistema de generaci\u00f3n energ\u00e9tica, democratizar el acceso y el consumo energ\u00e9tico, apostar por una propiedad colectiva que no deje a nadie fuera.\u00bb<\/p>\n<p>Desde Uni\u00f3n Renovables coinciden en que \u00ablas comunidades energ\u00e9ticas permiten el <strong>empoderamiento ciudadano<\/strong> y sit\u00faan el escenario fuera del &#8216;Matrix&#8217; en el que vivimos y proponen intentar pensar como hacer frente a situaciones de escasez energ\u00e9tica en t\u00e9rminos colectivos desde el mundo local, teniendo en cuenta siempre a las vecinas, sea cual sea su situaci\u00f3n personal e intentando repartir lo que se tenga, potenciando de este modo, el principio de solidaridad.\u00bb<\/p>\n<p>Por \u00faltimo, Gaia D&#8217;Elia, de BATEC, remarca que, aunque las comunidades energ\u00e9ticas \u00abpueden jugar un <strong>papel muy necesario en la transici\u00f3n ecosocial<\/strong>,\u00a0 tambi\u00e9n tienen el potencial de interrelacionarse con otros elementos transformadores para esta transici\u00f3n ecol\u00f3gica justa y solidaria desde el di\u00e1logo y la corresponsabilidad.\u00bb<\/p>\n<div id=\"attachment_225881\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-225881\" class=\"wp-image-225881 size-large\" src=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-200x133.jpg 200w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-300x200.jpg 300w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-400x267.jpg 400w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-600x400.jpg 600w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-768x512.jpg 768w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-800x533.jpg 800w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia-1024x683.jpg 1024w, https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/007A1672-copia.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-225881\" class=\"wp-caption-text\">Autor\u00eda: BATEC<\/p><\/div>\n<h4><strong>Seguros y finanzas \u00e9ticas al servicio de una transici\u00f3n ecol\u00f3gica justa y de base<\/strong><\/h4>\n<p>En Ar\u00e7 Cooperativa sabemos que las comunidades pueden ser una <strong>palanca para avanzar hacia una transici\u00f3n ecol\u00f3gica\u00a0<\/strong>que tenga en cuenta criterios de <strong>justicia y democracia.\u00a0<\/strong>Por este motivo, seguiremos acompa\u00f1ando a aquellos colectivos, ofreciendo <a href=\"https:\/\/arc.coop\/es\/servicios\/seguros-energias-renovables\/\">productos aseguradores espec\u00edficos<\/a> para sus necesidades. Otras entidades de las finanzas \u00e9ticas como <a href=\"https:\/\/www.fiarebancaetica.coop\/\" target=\"_blank\" rel=\"noopener\">Fiare Banca Etica<\/a> y\u00a0<a href=\"https:\/\/www.coop57.coop\/\" target=\"_blank\" rel=\"noopener\">Coop57<\/a> tambi\u00e9n est\u00e1n alineadas con esta apuesta, ofreciendo soluciones financieras que acompa\u00f1en a las comunidades energ\u00e9ticas.<\/p>\n<p>Las <strong>entidades de las finanzas \u00e9ticas<\/strong> trabajamos con la resta de la econom\u00eda solidaria para consolidar un <strong>ecosistema financiero al servicio del bien com\u00fan controlado desde la base<\/strong>. Un ecosistema financiero que redirija el flujo del cr\u00e9dito y la inversi\u00f3n hacia la resoluci\u00f3n de las necesidades sociales y ambientales. Ofrecer productos, servicios y acompa\u00f1amiento a las comunidades energ\u00e9ticas es una forma m\u00e1s de estar al <strong>servicio de esta transici\u00f3n ecol\u00f3gica justa y democr\u00e1tica<\/strong> de la que estamos participando.<\/p>\n<h4>Referencias:<\/h4>\n<p>[1] Som Comunitats (2022): \u00abGuia 1. Qu\u00e8 s\u00f3n les Comunitats Energ\u00e8tiques\u00bb. Fuente: <a href=\"https:\/\/somcomunitats.coop\/recursos\/\" target=\"_blank\" rel=\"noopener\">https:\/\/somcomunitats.coop\/recursos\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra apuesta por acompa\u00f1ar los proyectos alineados con una transici\u00f3n ecol\u00f3gica justa y democr\u00e1tica, estamos ofreciendo seguros espec\u00edficos para cubrir las necesidades aseguradoras de las comunidades energ\u00e9ticas. Estos colectivos, nacidos de la voluntad y la determinaci\u00f3n de grupos de personas para organizarse horizontalmente y de manera autogestionada, trabajan para un sistema energ\u00e9tico sostenible al servicio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":225855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[88],"tags":[1073,969,971,1095,1050],"class_list":["post-226065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es-2","tag-cel-coop-es","tag-comunitats-energetiques-es","tag-energia-renovable-es","tag-som-comunitats-es","tag-transicio-ecosocial-es-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas - Ar\u00e7 Cooperativa<\/title>\n<meta name=\"description\" content=\"Hemos conversado con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para ser un altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas - Ar\u00e7 Cooperativa\" \/>\n<meta property=\"og:description\" content=\"Hemos conversado con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para ser un altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\" \/>\n<meta property=\"og:site_name\" content=\"Ar\u00e7 Cooperativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/projectearc\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/projectearc\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T15:18:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T16:05:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arc_coop\" \/>\n<meta name=\"twitter:site\" content=\"@arc_coop\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\"},\"author\":{\"name\":\"Comunicaci\u00f3\",\"@id\":\"https:\/\/arc.coop\/es\/#\/schema\/person\/ce98a25a4c7244d25ab7b2661d5ec593\"},\"headline\":\"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas\",\"datePublished\":\"2024-04-22T15:18:38+00:00\",\"dateModified\":\"2024-04-22T16:05:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\"},\"wordCount\":1815,\"publisher\":{\"@id\":\"https:\/\/arc.coop\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg\",\"keywords\":[\"CEL Coop\",\"comunidades energ\u00e9ticas\",\"energia renovable\",\"Som Comunitats\",\"transici\u00f3 ecosocial\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\",\"url\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\",\"name\":\"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas - Ar\u00e7 Cooperativa\",\"isPartOf\":{\"@id\":\"https:\/\/arc.coop\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg\",\"datePublished\":\"2024-04-22T15:18:38+00:00\",\"dateModified\":\"2024-04-22T16:05:55+00:00\",\"description\":\"Hemos conversado con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para ser un altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.\",\"breadcrumb\":{\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage\",\"url\":\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg\",\"contentUrl\":\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg\",\"width\":800,\"height\":416},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/arc.coop\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arc.coop\/es\/#website\",\"url\":\"https:\/\/arc.coop\/es\/\",\"name\":\"Ar\u00e7 Cooperativa\",\"description\":\"Assegurem comprom\u00eds\",\"publisher\":{\"@id\":\"https:\/\/arc.coop\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arc.coop\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arc.coop\/es\/#organization\",\"name\":\"Ar\u00e7 Cooperativa\",\"url\":\"https:\/\/arc.coop\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arc.coop\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/06\/logo-arc\u00a6o.png\",\"contentUrl\":\"https:\/\/arc.coop\/wp-content\/uploads\/2024\/06\/logo-arc\u00a6o.png\",\"width\":400,\"height\":400,\"caption\":\"Ar\u00e7 Cooperativa\"},\"image\":{\"@id\":\"https:\/\/arc.coop\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/projectearc\/\",\"https:\/\/x.com\/arc_coop\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/arc.coop\/es\/#\/schema\/person\/ce98a25a4c7244d25ab7b2661d5ec593\",\"name\":\"Comunicaci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arc.coop\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/365dfcf0c88e1d20dea6f7afda28f94914bd66049b30541653a0d8bc52083f9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/365dfcf0c88e1d20dea6f7afda28f94914bd66049b30541653a0d8bc52083f9c?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3\"},\"sameAs\":[\"https:\/\/www.facebook.com\/projectearc\/\",\"https:\/\/x.com\/arc_coop\"],\"url\":\"https:\/\/arc.coop\/es\/author\/comunicacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas - Ar\u00e7 Cooperativa","description":"Hemos conversado con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para ser un altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/","og_locale":"es_ES","og_type":"article","og_title":"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas - Ar\u00e7 Cooperativa","og_description":"Hemos conversado con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para ser un altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.","og_url":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/","og_site_name":"Ar\u00e7 Cooperativa","article_publisher":"https:\/\/www.facebook.com\/projectearc\/","article_author":"https:\/\/www.facebook.com\/projectearc\/","article_published_time":"2024-04-22T15:18:38+00:00","article_modified_time":"2024-04-22T16:05:55+00:00","og_image":[{"width":800,"height":416,"url":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@arc_coop","twitter_site":"@arc_coop","twitter_misc":{"Escrito por":"Comunicaci\u00f3","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#article","isPartOf":{"@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/"},"author":{"name":"Comunicaci\u00f3","@id":"https:\/\/arc.coop\/es\/#\/schema\/person\/ce98a25a4c7244d25ab7b2661d5ec593"},"headline":"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas","datePublished":"2024-04-22T15:18:38+00:00","dateModified":"2024-04-22T16:05:55+00:00","mainEntityOfPage":{"@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/"},"wordCount":1815,"publisher":{"@id":"https:\/\/arc.coop\/es\/#organization"},"image":{"@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage"},"thumbnailUrl":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg","keywords":["CEL Coop","comunidades energ\u00e9ticas","energia renovable","Som Comunitats","transici\u00f3 ecosocial"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/","url":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/","name":"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas - Ar\u00e7 Cooperativa","isPartOf":{"@id":"https:\/\/arc.coop\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage"},"image":{"@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage"},"thumbnailUrl":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg","datePublished":"2024-04-22T15:18:38+00:00","dateModified":"2024-04-22T16:05:55+00:00","description":"Hemos conversado con entidades de referencia que agrupan y promueven las comunidades energ\u00e9ticas para ser un altavoz de propuestas que entienden la generaci\u00f3n y distribuci\u00f3n de energ\u00eda desde la participaci\u00f3n, el empoderamiento y la justicia social.","breadcrumb":{"@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#primaryimage","url":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg","contentUrl":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/04\/comunitats-energetiques-blog-2024-copia.jpg","width":800,"height":416},{"@type":"BreadcrumbList","@id":"https:\/\/arc.coop\/es\/2024\/04\/22\/comunidades-energeticas-mucho-mas-que-placas-solares-colectivas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/arc.coop\/es\/"},{"@type":"ListItem","position":2,"name":"Comunidades energ\u00e9ticas, mucho m\u00e1s que placas solares colectivas"}]},{"@type":"WebSite","@id":"https:\/\/arc.coop\/es\/#website","url":"https:\/\/arc.coop\/es\/","name":"Ar\u00e7 Cooperativa","description":"Assegurem comprom\u00eds","publisher":{"@id":"https:\/\/arc.coop\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arc.coop\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/arc.coop\/es\/#organization","name":"Ar\u00e7 Cooperativa","url":"https:\/\/arc.coop\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arc.coop\/es\/#\/schema\/logo\/image\/","url":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/06\/logo-arc\u00a6o.png","contentUrl":"https:\/\/arc.coop\/wp-content\/uploads\/2024\/06\/logo-arc\u00a6o.png","width":400,"height":400,"caption":"Ar\u00e7 Cooperativa"},"image":{"@id":"https:\/\/arc.coop\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/projectearc\/","https:\/\/x.com\/arc_coop"]},{"@type":"Person","@id":"https:\/\/arc.coop\/es\/#\/schema\/person\/ce98a25a4c7244d25ab7b2661d5ec593","name":"Comunicaci\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arc.coop\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/365dfcf0c88e1d20dea6f7afda28f94914bd66049b30541653a0d8bc52083f9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/365dfcf0c88e1d20dea6f7afda28f94914bd66049b30541653a0d8bc52083f9c?s=96&d=mm&r=g","caption":"Comunicaci\u00f3"},"sameAs":["https:\/\/www.facebook.com\/projectearc\/","https:\/\/x.com\/arc_coop"],"url":"https:\/\/arc.coop\/es\/author\/comunicacio\/"}]}},"_links":{"self":[{"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/posts\/226065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/comments?post=226065"}],"version-history":[{"count":5,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/posts\/226065\/revisions"}],"predecessor-version":[{"id":226072,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/posts\/226065\/revisions\/226072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/media\/225855"}],"wp:attachment":[{"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/media?parent=226065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/categories?post=226065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arc.coop\/es\/wp-json\/wp\/v2\/tags?post=226065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}